{"id":8044,"date":"2023-04-19T17:59:15","date_gmt":"2023-04-19T15:59:15","guid":{"rendered":"https:\/\/eat-life.fundesplai.org\/conferencies\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\/"},"modified":"2023-04-19T18:10:50","modified_gmt":"2023-04-19T16:10:50","slug":"version-en-ingles-conferencia-el-cambio-climatico-en-cataluna","status":"publish","type":"conferencies","link":"https:\/\/eat-life.fundesplai.org\/es\/conferencies\/version-en-ingles-conferencia-el-cambio-climatico-en-cataluna\/","title":{"rendered":"[Versi\u00f3n en ingl\u00e9s] Conferencia &#8216;El cambio clim\u00e1tico en Catalu\u00f1a&#8217;"},"content":{"rendered":"\n<p>La conferencia aborda el impacto del cambio clim\u00e1tico en Catalu\u00f1a y la afectaci\u00f3n en la alimentaci\u00f3n.<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"inline_featured_image":false},"class_list":["post-8044","conferencies","type-conferencies","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conferencia cambio clim\u00e1tico<\/title>\n<meta name=\"description\" content=\"La conferencia aborda el impacto del cambio clim\u00e1tico en Catalu\u00f1a y la afectaci\u00f3n que va a tener sobre la alimentaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conferencia cambio clim\u00e1tico\" \/>\n<meta property=\"og:description\" content=\"La conferencia aborda el impacto del cambio clim\u00e1tico en Catalu\u00f1a y la afectaci\u00f3n que va a tener sobre la alimentaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eat-life.fundesplai.org\/conferencies\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\/\" \/>\n<meta property=\"og:site_name\" content=\"EAT: LIFE\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-19T16:10:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eat-life.fundesplai.org\\\/conferencies\\\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\\\/\",\"url\":\"https:\\\/\\\/eat-life.fundesplai.org\\\/conferencies\\\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\\\/\",\"name\":\"Conferencia cambio clim\u00e1tico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eat-life.fundesplai.org\\\/#website\"},\"datePublished\":\"2023-04-19T15:59:15+00:00\",\"dateModified\":\"2023-04-19T16:10:50+00:00\",\"description\":\"La conferencia aborda el impacto del cambio clim\u00e1tico en Catalu\u00f1a y la afectaci\u00f3n que va a tener sobre la alimentaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eat-life.fundesplai.org\\\/conferencies\\\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eat-life.fundesplai.org\\\/conferencies\\\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eat-life.fundesplai.org\\\/conferencies\\\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Confer\u00e8ncies\",\"item\":\"https:\\\/\\\/eat-life.fundesplai.org\\\/conferencies\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Versi\u00f3n en ingl\u00e9s] Conferencia &#8216;El cambio clim\u00e1tico en Catalu\u00f1a&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eat-life.fundesplai.org\\\/#website\",\"url\":\"https:\\\/\\\/eat-life.fundesplai.org\\\/\",\"name\":\"EAT: LIFE\",\"description\":\"Una exposici\u00f3 tem\u00e0tica sobre el futur de l&#039;alimentaci\u00f3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eat-life.fundesplai.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conferencia cambio clim\u00e1tico","description":"La conferencia aborda el impacto del cambio clim\u00e1tico en Catalu\u00f1a y la afectaci\u00f3n que va a tener sobre la alimentaci\u00f3n.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Conferencia cambio clim\u00e1tico","og_description":"La conferencia aborda el impacto del cambio clim\u00e1tico en Catalu\u00f1a y la afectaci\u00f3n que va a tener sobre la alimentaci\u00f3n.","og_url":"https:\/\/eat-life.fundesplai.org\/conferencies\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\/","og_site_name":"EAT: LIFE","article_modified_time":"2023-04-19T16:10:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eat-life.fundesplai.org\/conferencies\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\/","url":"https:\/\/eat-life.fundesplai.org\/conferencies\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\/","name":"Conferencia cambio clim\u00e1tico","isPartOf":{"@id":"https:\/\/eat-life.fundesplai.org\/#website"},"datePublished":"2023-04-19T15:59:15+00:00","dateModified":"2023-04-19T16:10:50+00:00","description":"La conferencia aborda el impacto del cambio clim\u00e1tico en Catalu\u00f1a y la afectaci\u00f3n que va a tener sobre la alimentaci\u00f3n.","breadcrumb":{"@id":"https:\/\/eat-life.fundesplai.org\/conferencies\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eat-life.fundesplai.org\/conferencies\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eat-life.fundesplai.org\/conferencies\/versio-en-angles-conferencia-el-canvi-climatic-a-catalunya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Confer\u00e8ncies","item":"https:\/\/eat-life.fundesplai.org\/conferencies\/"},{"@type":"ListItem","position":2,"name":"[Versi\u00f3n en ingl\u00e9s] Conferencia &#8216;El cambio clim\u00e1tico en Catalu\u00f1a&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/eat-life.fundesplai.org\/#website","url":"https:\/\/eat-life.fundesplai.org\/","name":"EAT: LIFE","description":"Una exposici\u00f3 tem\u00e0tica sobre el futur de l&#039;alimentaci\u00f3","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eat-life.fundesplai.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/eat-life.fundesplai.org\/es\/wp-json\/wp\/v2\/conferencies\/8044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eat-life.fundesplai.org\/es\/wp-json\/wp\/v2\/conferencies"}],"about":[{"href":"https:\/\/eat-life.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/conferencies"}],"wp:attachment":[{"href":"https:\/\/eat-life.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=8044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}